{"id":778,"date":"2020-08-01T17:45:20","date_gmt":"2020-08-01T15:45:20","guid":{"rendered":"https:\/\/websurvey.cide.univr.it\/wpmpm\/?p=778"},"modified":"2020-08-05T11:12:14","modified_gmt":"2020-08-05T09:12:14","slug":"master-project-management-al-via-i-colloqui-di-orientamento-per-la-xiii-edizione","status":"publish","type":"post","link":"https:\/\/websurvey.cide.univr.it\/wpmpm\/778-master-project-management-al-via-i-colloqui-di-orientamento-per-la-xiii-edizione\/","title":{"rendered":"MASTER PROJECT MANAGEMENT: AL VIA I COLLOQUI DI ORIENTAMENTO PER LA XIII EDIZIONE"},"content":{"rendered":"<p>Aperti i colloqui di orientamento per la <strong>XIII edizione<\/strong> del <strong>master in project management<\/strong> (<strong>MPM<\/strong>). Il master forma specialisti nella gestione di progetti con l\u2019utilizzo metodiche di pianificazione e controllo di tempi, costi e qualit\u00e0.<\/p>\n<p>La figura del <em><strong>Project Manager<\/strong><\/em>, oltre a essere tra le pi\u00f9 richieste nel mercato del lavoro, concentra competenze eterogenee e trasversali ed \u00e8 in grado di coordinare professionisti diversi, con un forte orientamento al risultato e alla gestione totale del progetto.<\/p>\n<p>MPM \u00e8 un master universitario di primo livello dell\u2019<strong>Universit\u00e0 Degli Studi di Verona<\/strong> che ha gi\u00e0 diplomato pi\u00f9 di 150 partecipanti rivolto in modo particolare ma non esclusivo a giovani laureati tecnici che prima dell\u2019inizio vengono inseriti a tempo pieno in azienda (stage retribuito) e contemporaneamente impegnati in dieci mesi di formazione con la frequenza al master da gennaio a fine ottobre.<\/p>\n<p>Il master \u00e8 suddiviso in quattro moduli formativi: <strong>Project Management, Cost &amp; Revenue, Risk &amp; Contracts, Management by Projects<\/strong> con l\u2019obiettivo di affrontare tutti gli aspetti legati alla gestione di progetti complessi: dalla definizione della strategia fino al coordinamento di un team.<\/p>\n<p>Al termine del percorso \u00e8 prevista la redazione di un elaborato (<strong>Project work<\/strong>) realizzato in collaborazione con l\u2019azienda ospitante. MPM, master di project management, rende inoltre disponibile la frequenza a uno o pi\u00f9 dei suoi quattro moduli formativi (Project Management, Cost &amp; Revenue, Risk &amp; Contracts, Management by Projects) a imprenditori, dirigenti, quadri, collaboratori e liberi professionisti, anche non laureati.<\/p>\n<p>I colloqui di orientamento in modalit\u00e0 on line, per i candidati edizione del master MPM potranno essere effettuati contattando la direzione. I colloqui, gratuiti e senza impegno di iscrizione, vanno prenotati in anticipo concordando un appuntamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aperti i colloqui di orientamento per la XIII edizione del master in project management (MPM). Il master forma specialisti nella gestione di progetti con l\u2019utilizzo metodiche di pianificazione e controllo di tempi, costi e qualit\u00e0. La figura del Project Manager, <a href=\"https:\/\/websurvey.cide.univr.it\/wpmpm\/778-master-project-management-al-via-i-colloqui-di-orientamento-per-la-xiii-edizione\/\" class=\"read-more\">Read More &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/posts\/778"}],"collection":[{"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":1,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":780,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/posts\/778\/revisions\/780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/websurvey.cide.univr.it\/wpmpm\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}